{"id":1753,"date":"2024-05-29T21:18:51","date_gmt":"2024-05-29T19:18:51","guid":{"rendered":"https:\/\/comehome.network\/puestos-de-trabajo\/"},"modified":"2024-10-09T20:40:11","modified_gmt":"2024-10-09T18:40:11","slug":"puestos-de-trabajo","status":"publish","type":"page","link":"https:\/\/comehome.network\/es\/puestos-de-trabajo\/","title":{"rendered":"trabajo"},"content":{"rendered":"<section class=\"l-section wpb_row height_small with_img parallax_ver parallaxdir_reversed with_shape\"><div class=\"l-section-img\" role=\"img\" aria-label=\"Imagen\" data-img-width=\"1024\" data-img-height=\"500\" style=\"background-image: url(https:\/\/comehome.network\/wp-content\/uploads\/2024\/05\/ukraine_kinder_russland.jpg);background-position: top center;background-repeat: no-repeat;\"><\/div><div class=\"l-section-overlay\" style=\"background:rgba(0,0,0,0.30)\"><\/div><div class=\"l-section-shape type_zigzag pos_bottom\" style=\"height:15vmin;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 64 8\" preserveAspectRatio=\"none\" width=\"100%\" height=\"100%\">\r\n\t<path fill=\"currentColor\" d=\"M64 8 L0 8 L0 0 L20 7.9 L40 3 L48 5 L64 0 Z\"\/>\r\n<\/svg><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-separator size_custom\" style=\"height:150px\"><\/div><div class=\"wpb_text_column us_custom_98c5b2a3\"><div class=\"wpb_wrapper\"><h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u00bfQuieres participar activamente?<\/span><\/h1>\n<\/div><\/div><div class=\"g-cols wpb_row via_grid cols_1-2-1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><\/div><\/div><div class=\"wpb_column vc_column_container us_custom_6b868144\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column us_custom_98c5b2a3\"><div class=\"wpb_wrapper\"><h3 style=\"text-align: center;\"><span style=\"color: #ffff00;\">Haz que el mundo sea un poco mejor, as\u00ed que ayuda a darle forma de forma creativa y aporta tus ideas<\/span><\/h3>\n<h3 style=\"text-align: center;\"><\/h3>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><\/div><\/div><\/div><div class=\"w-separator size_custom\" style=\"height:200px\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Juntos por un futuro mejor<\/h2>\n<p><strong>En la Asociaci\u00f3n ComeHome perseguimos una misi\u00f3n clara y apol\u00edtica: la repatriaci\u00f3n de los ni\u00f1os ucranianos deportados y la reunificaci\u00f3n de las familias. Nuestro trabajo se basa en los valores de la moralidad, la \u00e9tica y la empat\u00eda. Creemos que el verdadero cambio y la ayuda sostenible pueden lograrse mediante la colaboraci\u00f3n y el trabajo en red. Por eso te buscamos activamente a ti y a tus ideas inspiradoras.<\/strong><\/p>\n<h3>Por qu\u00e9 te necesitamos<\/h3>\n<p>Para llevar a cabo con \u00e9xito nuestra misi\u00f3n, necesitamos un equipo dedicado de voluntarios, trabajadores aut\u00f3nomos y empleados a tiempo completo.<br \/>\nCada funci\u00f3n es fundamental para alcanzar nuestros objetivos y ayudar a los ni\u00f1os y familias afectados. He aqu\u00ed las razones por las que necesitamos tu apoyo:<\/p>\n<p><strong>1. Creatividad<\/strong> Tu energ\u00eda creativa es esencial para desarrollar soluciones innovadoras y hacer avanzar nuestros proyectos. Ya sea en comunicaci\u00f3n, marketing u organizaci\u00f3n de misiones, las ideas creativas marcan la diferencia y nos ayudan a encontrar nuevas formas de cumplir nuestra misi\u00f3n.<\/p>\n<p><strong>2. inspiraci\u00f3n<\/strong> Inspiraci\u00f3n La inspiraci\u00f3n es la chispa que nos impulsa. Tus pensamientos y acciones inspiradores motivan no s\u00f3lo al equipo, sino tambi\u00e9n a las personas a las que apoyamos. Juntos podemos crear historias inspiradoras que den esperanza y valor.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><strong>3. motivaci\u00f3n<\/strong> La motivaci\u00f3n es la fuerza motriz de nuestro compromiso. Tu motivaci\u00f3n para hacer el bien y ayudar a los dem\u00e1s refuerza nuestra misi\u00f3n compartida. Garantiza que perseveremos incluso en tiempos dif\u00edciles y sigamos luchando para mejorar la vida de muchos ni\u00f1os y familias.<\/p>\n<p><strong>4. comunicaci\u00f3n<\/strong> La comunicaci\u00f3n eficaz es la clave del \u00e9xito. Tu capacidad para comunicarte de forma clara y persuasiva nos ayuda a difundir nuestro mensaje, ganar simpatizantes y coordinar nuestro trabajo de forma eficaz. Una buena comunicaci\u00f3n nos conecta con las personas que necesitan nuestra ayuda y con quienes nos apoyan.<\/p>\n<p><strong>5. Pasi\u00f3n<\/strong> La pasi\u00f3n est\u00e1 en el coraz\u00f3n de nuestro trabajo. Tu pasi\u00f3n por nuestra misi\u00f3n y tu voluntad de darlo todo marcan la diferencia. Nos impulsa a dar lo mejor de nosotros mismos cada d\u00eda y a no rendirnos nunca.<\/p>\n<h3>Tu apoyo cuenta<\/h3>\n<p>Ya seas voluntario, aut\u00f3nomo o empleado a tiempo completo, toda forma de participaci\u00f3n es valiosa y necesaria. Juntos podemos formar una comunidad fuerte, creativa y motivada que trabaje incansablemente para repatriar a los menores deportados y reunir a las familias. <strong>Forma parte de nuestro equipo y apoya a la Asociaci\u00f3n ComeHome. Juntos, con creatividad, inspiraci\u00f3n, motivaci\u00f3n, comunicaci\u00f3n y pasi\u00f3n, podemos lograr grandes cosas y marcar una diferencia duradera en la vida de muchas personas.<\/strong> Esperamos verte y te agradecemos tu apoyo.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small with_shape\"><div class=\"l-section-overlay\" style=\"background:var(--color-alt-content-primary)\"><\/div><div class=\"l-section-shape type_zigzag pos_top\" style=\"height:15vmin;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 64 8\" preserveAspectRatio=\"none\" width=\"100%\" height=\"100%\">\r\n\t<path fill=\"currentColor\" d=\"M64 8 L0 8 L0 0 L20 7.9 L40 3 L48 5 L64 0 Z\"\/>\r\n<\/svg><\/div><div class=\"l-section-shape type_zigzag pos_bottom\" style=\"height:15vmin;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 64 8\" preserveAspectRatio=\"none\" width=\"100%\" height=\"100%\">\r\n\t<path fill=\"currentColor\" d=\"M64 8 L0 8 L0 0 L20 7.9 L40 3 L48 5 L64 0 Z\"\/>\r\n<\/svg><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-separator size_custom\" style=\"height:100px\"><\/div><div class=\"wpb_text_column us_custom_a3ef950d\"><div class=\"wpb_wrapper\"><h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u00bfD\u00f3nde necesitamos actualmente tu apoyo?<\/span><\/h1>\n<\/div><\/div><div class=\"wpb_text_column us_custom_67cdd32e has_text_color\"><div class=\"wpb_wrapper\"><h3 style=\"text-align: center;\"><span style=\"color: #ffff00;\">Todas las formas en que puedes apoyarnos, esperamos tus noticias<\/span><\/h3>\n<\/div><\/div>\n<div class=\"vc_grid-container-wrapper vc_clearfix vc_grid-animation-fadeIn\">\n\t<div class=\"vc_grid-container vc_clearfix wpb_content_element vc_basic_grid\" data-initial-loading-animation=\"fadeIn\" data-vc-grid-settings=\"{&quot;page_id&quot;:1753,&quot;style&quot;:&quot;all&quot;,&quot;action&quot;:&quot;vc_get_vc_grid_data&quot;,&quot;shortcode_id&quot;:&quot;1728499148730-92ebabf9-6d8d-8&quot;,&quot;tag&quot;:&quot;vc_basic_grid&quot;}\" data-vc-request=\"https:\/\/comehome.network\/wp-admin\/admin-ajax.php?lang=es\" data-vc-post-id=\"1753\" data-vc-public-nonce=\"b4ecf93748\">\n\t\t<style data-type=\"vc_shortcodes-custom-css\">.vc_custom_1419240595465{background-color: #f9f9f9 !important;}.vc_custom_1419240793832{background-color: rgba(0,0,0,0.3) !important;*background-color: rgb(0,0,0) !important;}<\/style><div class=\"vc_grid vc_row vc_grid-gutter-30px vc_pageable-wrapper vc_hook_hover\" data-vc-pageable-content=\"true\"><div class=\"vc_pageable-slide-wrapper vc_clearfix\" data-vc-grid-content=\"true\"><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix \"><div class=\"vc_gitem-animated-block  vc_gitem-animate vc_gitem-animate-scaleRotateIn\"  data-vc-animation=\"scaleRotateIn\"><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-16-9 vc_gitem-is-link\" style=\"background-image: url('https:\/\/comehome.network\/wp-content\/uploads\/2024\/08\/fundraising.jpg') !important;\"><a href=\"https:\/\/comehome.network\/es\/jobs\/conviertete-en-un-experto-en-recaudacion-de-fondos\/\" title=\"Convi\u00e9rtete en un experto en recaudaci\u00f3n de fondos\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img decoding=\"async\" class=\"vc_gitem-zone-img\" src=\"https:\/\/comehome.network\/wp-content\/uploads\/2024\/08\/fundraising.jpg\" alt=\"\u00bfEres un experto en captaci\u00f3n de fondos que sabe c\u00f3mo movilizar a la gente y gan\u00e1rsela para una buena causa? Presenta tu candidatura aqu\u00ed\" loading=\"lazy\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-b vc_custom_1419240793832 vc-gitem-zone-height-mode-auto vc_gitem-is-link\"><a href=\"https:\/\/comehome.network\/es\/jobs\/conviertete-en-un-experto-en-recaudacion-de-fondos\/\" title=\"Convi\u00e9rtete en un experto en recaudaci\u00f3n de fondos\" class=\"vc_gitem-link vc-zone-link\" ><\/a><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240595465\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Convi\u00e9rtete en un experto en recaudaci\u00f3n de fondos<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>\u00bfEres un experto en captaci\u00f3n de fondos que sabe c\u00f3mo movilizar a la gente y gan\u00e1rsela para una buena causa? Presenta tu candidatura aqu\u00ed <\/p>\n<\/p><\/div><div class=\"vc_btn3-container  wpb_animate_when_almost_visible wpb_bounceIn bounceIn vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" a href=\"https:\/\/comehome.network\/es\/jobs\/conviertete-en-un-experto-en-recaudacion-de-fondos\/\" class=\"vc_gitem-link vc_general vc_btn3 vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" target=\"_blank\" target=\"_blank\" title=\"Weiterlesen\"><i class=\"vc_btn3-icon fas fa-chevron-right\"><\/i> Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix \"><div class=\"vc_gitem-animated-block  vc_gitem-animate vc_gitem-animate-scaleRotateIn\"  data-vc-animation=\"scaleRotateIn\"><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-16-9 vc_gitem-is-link\" style=\"background-image: url('https:\/\/comehome.network\/wp-content\/uploads\/2024\/07\/uk2.jpg') !important;\"><a href=\"https:\/\/comehome.network\/es\/jobs\/responsable-de-medios-sociales\/\" title=\"Responsable de Medios Sociales\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img decoding=\"async\" class=\"vc_gitem-zone-img\" src=\"https:\/\/comehome.network\/wp-content\/uploads\/2024\/07\/uk2.jpg\" alt=\"\u00bfEres un entusiasta de las redes sociales con talento para el pensamiento estrat\u00e9gico y un don para la comunicaci\u00f3n eficaz?\" loading=\"lazy\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-b vc_custom_1419240793832 vc-gitem-zone-height-mode-auto vc_gitem-is-link\"><a href=\"https:\/\/comehome.network\/es\/jobs\/responsable-de-medios-sociales\/\" title=\"Responsable de Medios Sociales\" class=\"vc_gitem-link vc-zone-link\" ><\/a><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240595465\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Responsable de Medios Sociales<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>\u00bfEres un entusiasta de las redes sociales con talento para el pensamiento estrat\u00e9gico y un don para la comunicaci\u00f3n eficaz?<\/p>\n<\/p><\/div><div class=\"vc_btn3-container  wpb_animate_when_almost_visible wpb_bounceIn bounceIn vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" a href=\"https:\/\/comehome.network\/es\/jobs\/responsable-de-medios-sociales\/\" class=\"vc_gitem-link vc_general vc_btn3 vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" target=\"_blank\" target=\"_blank\" title=\"Weiterlesen\"><i class=\"vc_btn3-icon fas fa-chevron-right\"><\/i> Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix \"><div class=\"vc_gitem-animated-block  vc_gitem-animate vc_gitem-animate-scaleRotateIn\"  data-vc-animation=\"scaleRotateIn\"><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-16-9 vc_gitem-is-link\" style=\"background-image: url('https:\/\/comehome.network\/wp-content\/uploads\/2024\/06\/social-media-manager.jpg') !important;\"><a href=\"https:\/\/comehome.network\/es\/jobs\/creador-de-contenidos-creativos\/\" title=\"Creador de contenidos creativos\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img decoding=\"async\" class=\"vc_gitem-zone-img\" src=\"https:\/\/comehome.network\/wp-content\/uploads\/2024\/06\/social-media-manager.jpg\" alt=\"\u00bfEres una mente creativa con talento para contar historias y un don para las redes sociales? Entonces este es tu trabajo\" loading=\"lazy\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-b vc_custom_1419240793832 vc-gitem-zone-height-mode-auto vc_gitem-is-link\"><a href=\"https:\/\/comehome.network\/es\/jobs\/creador-de-contenidos-creativos\/\" title=\"Creador de contenidos creativos\" class=\"vc_gitem-link vc-zone-link\" ><\/a><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240595465\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Creador de contenidos creativos<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>\u00bfEres una mente creativa con talento para contar historias y un don para las redes sociales? Entonces este es tu trabajo <\/p>\n<\/p><\/div><div class=\"vc_btn3-container  wpb_animate_when_almost_visible wpb_bounceIn bounceIn vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" a href=\"https:\/\/comehome.network\/es\/jobs\/creador-de-contenidos-creativos\/\" class=\"vc_gitem-link vc_general vc_btn3 vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" target=\"_blank\" target=\"_blank\" title=\"Weiterlesen\"><i class=\"vc_btn3-icon fas fa-chevron-right\"><\/i> Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix \"><div class=\"vc_gitem-animated-block  vc_gitem-animate vc_gitem-animate-scaleRotateIn\"  data-vc-animation=\"scaleRotateIn\"><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-16-9 vc_gitem-is-link\" style=\"background-image: url('https:\/\/comehome.network\/wp-content\/uploads\/2024\/07\/video1.jpg') !important;\"><a href=\"https:\/\/comehome.network\/es\/jobs\/creador-creativo-de-videos\/\" title=\"Creador creativo de v\u00eddeos\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img decoding=\"async\" class=\"vc_gitem-zone-img\" src=\"https:\/\/comehome.network\/wp-content\/uploads\/2024\/07\/video1.jpg\" alt=\"\u00bfEres un visionario creativo con talento para contar historias a trav\u00e9s de im\u00e1genes en movimiento?\r\nEntonces nos gustar\u00eda inspirarte para esta tarea.\" loading=\"lazy\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-b vc_custom_1419240793832 vc-gitem-zone-height-mode-auto vc_gitem-is-link\"><a href=\"https:\/\/comehome.network\/es\/jobs\/creador-creativo-de-videos\/\" title=\"Creador creativo de v\u00eddeos\" class=\"vc_gitem-link vc-zone-link\" ><\/a><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240595465\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Creador creativo de v\u00eddeos<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>\u00bfEres un visionario creativo con talento para contar historias a trav\u00e9s de im\u00e1genes en movimiento?<br \/>\nEntonces nos gustar\u00eda inspirarte para esta tarea. <\/p>\n<\/p><\/div><div class=\"vc_btn3-container  wpb_animate_when_almost_visible wpb_bounceIn bounceIn vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" a href=\"https:\/\/comehome.network\/es\/jobs\/creador-creativo-de-videos\/\" class=\"vc_gitem-link vc_general vc_btn3 vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" target=\"_blank\" target=\"_blank\" title=\"Weiterlesen\"><i class=\"vc_btn3-icon fas fa-chevron-right\"><\/i> Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix \"><div class=\"vc_gitem-animated-block  vc_gitem-animate vc_gitem-animate-scaleRotateIn\"  data-vc-animation=\"scaleRotateIn\"><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-16-9 vc_gitem-is-link\" style=\"background-image: url('https:\/\/comehome.network\/wp-content\/uploads\/2024\/07\/office2.jpg') !important;\"><a href=\"https:\/\/comehome.network\/es\/jobs\/oficina-y-gestion-de-oficinas\/\" title=\"Oficina y gesti\u00f3n de oficinas\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img decoding=\"async\" class=\"vc_gitem-zone-img\" src=\"https:\/\/comehome.network\/wp-content\/uploads\/2024\/07\/office2.jpg\" alt=\"\u00bfTienes talento organizativo, ojo para los detalles y pasi\u00f3n por la justicia social?\" loading=\"lazy\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-b vc_custom_1419240793832 vc-gitem-zone-height-mode-auto vc_gitem-is-link\"><a href=\"https:\/\/comehome.network\/es\/jobs\/oficina-y-gestion-de-oficinas\/\" title=\"Oficina y gesti\u00f3n de oficinas\" class=\"vc_gitem-link vc-zone-link\" ><\/a><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240595465\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Oficina y gesti\u00f3n de oficinas<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>\u00bfTienes talento organizativo, ojo para los detalles y pasi\u00f3n por la justicia social?<\/p>\n<\/p><\/div><div class=\"vc_btn3-container  wpb_animate_when_almost_visible wpb_bounceIn bounceIn vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" a href=\"https:\/\/comehome.network\/es\/jobs\/oficina-y-gestion-de-oficinas\/\" class=\"vc_gitem-link vc_general vc_btn3 vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" target=\"_blank\" target=\"_blank\" title=\"Weiterlesen\"><i class=\"vc_btn3-icon fas fa-chevron-right\"><\/i> Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix \"><div class=\"vc_gitem-animated-block  vc_gitem-animate vc_gitem-animate-scaleRotateIn\"  data-vc-animation=\"scaleRotateIn\"><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-16-9 vc_gitem-is-link\" style=\"background-image: url('https:\/\/comehome.network\/wp-content\/uploads\/2024\/07\/seminar1.jpg') !important;\"><a href=\"https:\/\/comehome.network\/es\/jobs\/moderador-dedicado-para-veladas-informativas-y-talleres\/\" title=\"Moderador dedicado para veladas informativas y talleres\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img decoding=\"async\" class=\"vc_gitem-zone-img\" src=\"https:\/\/comehome.network\/wp-content\/uploads\/2024\/07\/seminar1.jpg\" alt=\"\u00bfTe apasiona informar a la gente, responder preguntas y dar charlas?\" loading=\"lazy\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-b vc_custom_1419240793832 vc-gitem-zone-height-mode-auto vc_gitem-is-link\"><a href=\"https:\/\/comehome.network\/es\/jobs\/moderador-dedicado-para-veladas-informativas-y-talleres\/\" title=\"Moderador dedicado para veladas informativas y talleres\" class=\"vc_gitem-link vc-zone-link\" ><\/a><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240595465\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Moderador dedicado para veladas informativas y talleres<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>\u00bfTe apasiona informar a la gente, responder preguntas y dar charlas?<\/p>\n<\/p><\/div><div class=\"vc_btn3-container  wpb_animate_when_almost_visible wpb_bounceIn bounceIn vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" a href=\"https:\/\/comehome.network\/es\/jobs\/moderador-dedicado-para-veladas-informativas-y-talleres\/\" class=\"vc_gitem-link vc_general vc_btn3 vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" target=\"_blank\" target=\"_blank\" title=\"Weiterlesen\"><i class=\"vc_btn3-icon fas fa-chevron-right\"><\/i> Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix \"><div class=\"vc_gitem-animated-block  vc_gitem-animate vc_gitem-animate-scaleRotateIn\"  data-vc-animation=\"scaleRotateIn\"><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-16-9 vc_gitem-is-link\" style=\"background-image: url('https:\/\/comehome.network\/wp-content\/uploads\/2024\/06\/angels.jpg') !important;\"><a href=\"https:\/\/comehome.network\/es\/jobs\/apoyo-a-nuestros-miembros\/\" title=\"Apoyo a nuestros miembros\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img decoding=\"async\" class=\"vc_gitem-zone-img\" src=\"https:\/\/comehome.network\/wp-content\/uploads\/2024\/06\/angels.jpg\" alt=\"La Asociaci\u00f3n ComeHome est\u00e1 buscando un miembro del personal comprometido y amable para el apoyo a los miembros\" loading=\"lazy\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-b vc_custom_1419240793832 vc-gitem-zone-height-mode-auto vc_gitem-is-link\"><a href=\"https:\/\/comehome.network\/es\/jobs\/apoyo-a-nuestros-miembros\/\" title=\"Apoyo a nuestros miembros\" class=\"vc_gitem-link vc-zone-link\" ><\/a><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240595465\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Apoyo a nuestros miembros<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>La Asociaci\u00f3n ComeHome est\u00e1 buscando un miembro del personal comprometido y amable para el apoyo a los miembros<\/p>\n<\/p><\/div><div class=\"vc_btn3-container  wpb_animate_when_almost_visible wpb_bounceIn bounceIn vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" a href=\"https:\/\/comehome.network\/es\/jobs\/apoyo-a-nuestros-miembros\/\" class=\"vc_gitem-link vc_general vc_btn3 vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" target=\"_blank\" target=\"_blank\" title=\"Weiterlesen\"><i class=\"vc_btn3-icon fas fa-chevron-right\"><\/i> Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix \"><div class=\"vc_gitem-animated-block  vc_gitem-animate vc_gitem-animate-scaleRotateIn\"  data-vc-animation=\"scaleRotateIn\"><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-16-9 vc_gitem-is-link\" style=\"background-image: url('https:\/\/comehome.network\/wp-content\/uploads\/2024\/07\/affiliate-partner.jpg') !important;\"><a href=\"https:\/\/comehome.network\/es\/jobs\/gestion-de-afiliados-y-socios\/\" title=\"Gesti\u00f3n de afiliados y socios\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img decoding=\"async\" class=\"vc_gitem-zone-img\" src=\"https:\/\/comehome.network\/wp-content\/uploads\/2024\/07\/affiliate-partner.jpg\" alt=\"\u00bfEst\u00e1s familiarizado con los programas de socios y afiliados y te apasiona gestionar estructuras de socios? Presenta tu candidatura aqu\u00ed.\" loading=\"lazy\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-b vc_custom_1419240793832 vc-gitem-zone-height-mode-auto vc_gitem-is-link\"><a href=\"https:\/\/comehome.network\/es\/jobs\/gestion-de-afiliados-y-socios\/\" title=\"Gesti\u00f3n de afiliados y socios\" class=\"vc_gitem-link vc-zone-link\" ><\/a><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240595465\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Gesti\u00f3n de afiliados y socios<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>\u00bfEst\u00e1s familiarizado con los programas de socios y afiliados y te apasiona gestionar estructuras de socios? Presenta tu candidatura aqu\u00ed. <\/p>\n<\/p><\/div><div class=\"vc_btn3-container  wpb_animate_when_almost_visible wpb_bounceIn bounceIn vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" a href=\"https:\/\/comehome.network\/es\/jobs\/gestion-de-afiliados-y-socios\/\" class=\"vc_gitem-link vc_general vc_btn3 vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" target=\"_blank\" target=\"_blank\" title=\"Weiterlesen\"><i class=\"vc_btn3-icon fas fa-chevron-right\"><\/i> Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><\/div><\/div>\n\t<\/div>\n<\/div><div class=\"w-separator size_custom\" style=\"height:150px\"><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"\u00bfQuieres participar activamente? Haz que el mundo sea un poco mejor, as\u00ed que ayuda a darle forma de forma creativa y aporta tus ideas Juntos por un futuro mejor En la Asociaci\u00f3n ComeHome perseguimos una misi\u00f3n clara y apol\u00edtica: la repatriaci\u00f3n de los ni\u00f1os ucranianos deportados y la reunificaci\u00f3n de las familias. Nuestro trabajo se...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"give_campaign_id":0,"pmpro_default_level":"","episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","iawp_total_views":0,"footnotes":""},"class_list":["post-1753","page","type-page","status-publish","hentry","pmpro-has-access"],"acf":[],"campaignId":"","_links":{"self":[{"href":"https:\/\/comehome.network\/es\/wp-json\/wp\/v2\/pages\/1753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comehome.network\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/comehome.network\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/comehome.network\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comehome.network\/es\/wp-json\/wp\/v2\/comments?post=1753"}],"version-history":[{"count":22,"href":"https:\/\/comehome.network\/es\/wp-json\/wp\/v2\/pages\/1753\/revisions"}],"predecessor-version":[{"id":6344,"href":"https:\/\/comehome.network\/es\/wp-json\/wp\/v2\/pages\/1753\/revisions\/6344"}],"wp:attachment":[{"href":"https:\/\/comehome.network\/es\/wp-json\/wp\/v2\/media?parent=1753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}