{"id":4211,"date":"2024-07-08T19:19:35","date_gmt":"2024-07-08T17:19:35","guid":{"rendered":"https:\/\/comehome.network\/proyectos\/"},"modified":"2024-10-09T22:07:25","modified_gmt":"2024-10-09T20:07:25","slug":"proyectos","status":"publish","type":"page","link":"https:\/\/comehome.network\/es\/proyectos\/","title":{"rendered":"Proyectos"},"content":{"rendered":"<section class=\"l-section wpb_row height_small with_img parallax_ver parallaxdir_reversed with_shape\"><div class=\"l-section-img\" role=\"img\" aria-label=\"Imagen\" data-img-width=\"1500\" data-img-height=\"1000\" style=\"background-image: url(https:\/\/comehome.network\/wp-content\/uploads\/2024\/10\/comehome.jpg);background-position: top center;background-repeat: no-repeat;\"><\/div><div class=\"l-section-overlay\" style=\"background:rgba(0,0,0,0.30)\"><\/div><div class=\"l-section-shape type_zigzag pos_bottom\" style=\"height:15vmin;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 64 8\" preserveAspectRatio=\"none\" width=\"100%\" height=\"100%\">\r\n\t<path fill=\"currentColor\" d=\"M64 8 L0 8 L0 0 L20 7.9 L40 3 L48 5 L64 0 Z\"\/>\r\n<\/svg><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-separator size_custom\" style=\"height:150px\"><\/div><div class=\"wpb_text_column us_custom_98c5b2a3\"><div class=\"wpb_wrapper\"><h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\">Dar esperanza, asegurar el futuro &#8211; \u00a1Apoya a ComeHome!<\/span><\/h1>\n<\/div><\/div><div class=\"g-cols wpb_row via_grid cols_1-2-1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><\/div><\/div><div class=\"wpb_column vc_column_container us_custom_6b868144\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column us_custom_98c5b2a3\"><div class=\"wpb_wrapper\"><h3 style=\"text-align: center;\"><span style=\"color: #ffff00;\">Haciendo el mundo un poco mejor &#8211; mano a mano por un futuro mejor &#8211; \u00a1dona ahora! <\/span><\/h3>\n<\/div><\/div><div class=\"wpb_text_column us_custom_98c5b2a3\"><div class=\"wpb_wrapper\"><h3 style=\"text-align: center;\"><span style=\"color: #ffff00;\"><span style=\"color: #ffffff;\">donaci\u00f3n segura<\/span><br \/>\n<\/span><\/h3>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><\/div><\/div><\/div><div class=\"w-separator size_custom\" style=\"height:200px\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Tu apoyo espec\u00edfico a proyectos probados e importantes<\/h2>\n<p><strong>\u00a1Bienvenido a la Asociaci\u00f3n ComeHome!<\/strong> Entendemos que cada donante tiene diferentes preocupaciones y preferencias en cuanto al destino de su donaci\u00f3n.<br \/>\nPor este motivo, hemos dise\u00f1ado nuestro programa de donaciones para que puedas donar espec\u00edficamente a proyectos que te resulten especialmente cercanos. Este enfoque te permite hacer una contribuci\u00f3n directa y personal que beneficia exactamente a las \u00e1reas que son importantes para ti.<\/p>\n<h4>\u00bfPor qu\u00e9 donaciones individuales?<\/h4>\n<p><strong>Apoyo espec\u00edfico<\/strong>: Con las donaciones individuales, tienes la oportunidad de elegir exactamente el proyecto que m\u00e1s te atraiga.Ya se trate de atenci\u00f3n m\u00e9dica, apoyo psicol\u00f3gico, programas educativos o alojamiento seguro, tu donativo va exactamente donde t\u00fa quieres que vaya.<\/p>\n<p><strong>Transparencia y confianza<\/strong>: Todos nuestros proyectos se auditan y supervisan exhaustivamente. Garantizamos una total transparencia para que puedas estar seguro de que tu donativo se utiliza de forma eficaz y responsable. Recibir\u00e1s actualizaciones e informes peri\u00f3dicos sobre el progreso y el impacto de tu ayuda.<\/p>\n<p><strong>Ayuda eficaz<\/strong>: Al poder hacer donaciones espec\u00edficas, puedes maximizar la eficacia de tu donaci\u00f3n. Contribuyes directamente a satisfacer necesidades espec\u00edficas y a resolver problemas concretos. Esto no s\u00f3lo refuerza los propios proyectos, sino tambi\u00e9n tu confianza en los cambios positivos que haces posibles.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><strong>Proyectos importantes y examinados<\/strong>: Cada uno de nuestros proyectos ha sido cuidadosamente seleccionado y examinado para garantizar que satisface las necesidades m\u00e1s urgentes y relevantes. Nuestras organizaciones asociadas y nosotros colaboramos estrechamente para garantizar que los fondos llegan all\u00ed donde se necesitan con m\u00e1s urgencia.<\/p>\n<h3>C\u00f3mo puedes ayudar<\/h3>\n<p><strong>Sencillo y eficaz<\/strong>: Visita nuestra p\u00e1gina de proyectos y elige el proyecto que m\u00e1s te conmueva. Cada cantidad que dones ayuda a mejorar la vida de los ni\u00f1os y las familias afectadas.<\/p>\n<p><strong>Forma parte de la soluci\u00f3n<\/strong>: Con tu donaci\u00f3n espec\u00edfica, formas parte activa de la soluci\u00f3n. Ayudas a financiar proyectos vitales y a llevar esperanza y apoyo directamente a quienes m\u00e1s lo necesitan.<\/p>\n<p><strong>Actualizaciones peri\u00f3dicas<\/strong>: Mantente informado sobre el progreso y el \u00e9xito de los proyectos que has apoyado. Te mantendremos al d\u00eda y te mostraremos los cambios positivos que tu donaci\u00f3n ha hecho posibles.<\/p>\n<p><strong>Conseguir m\u00e1s juntos<\/strong>: Cada contribuci\u00f3n cuenta. Junto con otros donantes, podemos conseguir grandes cosas y lograr mejoras duraderas para los ni\u00f1os y las familias afectadas.<\/p>\n<p><strong>\u00a1Haz un donativo ahora y marca la diferencia!<\/strong> Tu apoyo es un signo de esperanza y compasi\u00f3n. Elige tu proyecto favorito y ay\u00fadanos a crear juntos un futuro mejor para los ni\u00f1os ucranianos.<\/p>\n<p><strong>Asociaci\u00f3n ComeHome &#8211; Juntos fuertes por el futuro de los ni\u00f1os.<\/strong> \u00a1Muchas gracias por tu valioso apoyo!<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small with_shape\"><div class=\"l-section-overlay\" style=\"background:var(--color-content-primary)\"><\/div><div class=\"l-section-shape type_zigzag pos_top\" style=\"height:15vmin;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 64 8\" preserveAspectRatio=\"none\" width=\"100%\" height=\"100%\">\r\n\t<path fill=\"currentColor\" d=\"M64 8 L0 8 L0 0 L20 7.9 L40 3 L48 5 L64 0 Z\"\/>\r\n<\/svg><\/div><div class=\"l-section-shape type_zigzag pos_bottom\" style=\"height:15vmin;\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 64 8\" preserveAspectRatio=\"none\" width=\"100%\" height=\"100%\">\r\n\t<path fill=\"currentColor\" d=\"M64 8 L0 8 L0 0 L20 7.9 L40 3 L48 5 L64 0 Z\"\/>\r\n<\/svg><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-separator size_custom\" style=\"height:100px\"><\/div><div class=\"wpb_text_column us_custom_a3ef950d\"><div class=\"wpb_wrapper\"><h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\">Donde hay necesidad, tu contribuci\u00f3n ayuda: \u00a1tu ayuda marca la diferencia!<\/span><\/h1>\n<\/div><\/div><div class=\"wpb_text_column us_custom_f48eea97 has_text_color\"><div class=\"wpb_wrapper\"><h3 style=\"text-align: center;\"><span style=\"color: #ffff00;\">Con tu ayuda podemos conseguir m\u00e1s: \u00a1forma parte de ello!<\/span><\/h3>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div>\n<div class=\"vc_grid-container-wrapper vc_clearfix vc_grid-animation-fadeIn\">\n\t<div class=\"vc_grid-container vc_clearfix wpb_content_element vc_basic_grid\" data-initial-loading-animation=\"fadeIn\" data-vc-grid-settings=\"{&quot;page_id&quot;:4211,&quot;style&quot;:&quot;all&quot;,&quot;action&quot;:&quot;vc_get_vc_grid_data&quot;,&quot;shortcode_id&quot;:&quot;1728504365815-9eb6ee1a-350a-8&quot;,&quot;tag&quot;:&quot;vc_basic_grid&quot;}\" data-vc-request=\"https:\/\/comehome.network\/wp-admin\/admin-ajax.php?lang=es\" data-vc-post-id=\"4211\" data-vc-public-nonce=\"b4ecf93748\">\n\t\t<style data-type=\"vc_shortcodes-custom-css\">.vc_custom_1419240595465{background-color: #f9f9f9 !important;}.vc_custom_1419240793832{background-color: rgba(0,0,0,0.3) !important;*background-color: rgb(0,0,0) !important;}<\/style><div class=\"vc_grid vc_row vc_grid-gutter-10px vc_pageable-wrapper vc_hook_hover\" data-vc-pageable-content=\"true\"><div class=\"vc_pageable-slide-wrapper vc_clearfix\" data-vc-grid-content=\"true\"><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix \"><div class=\"vc_gitem-animated-block  vc_gitem-animate vc_gitem-animate-scaleRotateIn\"  data-vc-animation=\"scaleRotateIn\"><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-16-9 vc_gitem-is-link\" style=\"background-image: url('https:\/\/comehome.network\/wp-content\/uploads\/2024\/08\/buero7.jpg') !important;\"><a href=\"https:\/\/comehome.network\/es\/einzelspende\/la-base-de-la-asociacion-comehome-apoyar-el-desarrollo-de\/\" title=\"La base de la Asociaci\u00f3n ComeHome, apoyar el desarrollo de\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img decoding=\"async\" class=\"vc_gitem-zone-img\" src=\"https:\/\/comehome.network\/wp-content\/uploads\/2024\/08\/buero7.jpg\" alt=\"Cada contribuci\u00f3n cuenta. Juntos podemos conseguir que estos ni\u00f1os no caigan en el olvido y que sus familias puedan volver a abrazarlos pronto. .\" loading=\"lazy\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-b vc_custom_1419240793832 vc-gitem-zone-height-mode-auto vc_gitem-is-link\"><a href=\"https:\/\/comehome.network\/es\/einzelspende\/la-base-de-la-asociacion-comehome-apoyar-el-desarrollo-de\/\" title=\"La base de la Asociaci\u00f3n ComeHome, apoyar el desarrollo de\" class=\"vc_gitem-link vc-zone-link\" ><\/a><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240595465\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >La base de la Asociaci\u00f3n ComeHome, apoyar el desarrollo de<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" ><p>Cada contribuci\u00f3n cuenta. Juntos podemos conseguir que estos ni\u00f1os no caigan en el olvido y que sus familias puedan volver a abrazarlos pronto. .<\/p>\n<\/p><\/div><div class=\"vc_btn3-container  wpb_animate_when_almost_visible wpb_bounceIn bounceIn vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" a href=\"https:\/\/comehome.network\/es\/einzelspende\/la-base-de-la-asociacion-comehome-apoyar-el-desarrollo-de\/\" class=\"vc_gitem-link vc_general vc_btn3 vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" target=\"_blank\" target=\"_blank\" title=\"Weiterlesen\"><i class=\"vc_btn3-icon fas fa-chevron-right\"><\/i> Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><div class=\"vc_grid-item vc_clearfix vc_col-sm-4 vc_grid-item-zone-c-bottom\"><div class=\"vc_grid-item-mini vc_clearfix \"><div class=\"vc_gitem-animated-block  vc_gitem-animate vc_gitem-animate-scaleRotateIn\"  data-vc-animation=\"scaleRotateIn\"><div class=\"vc_gitem-zone vc_gitem-zone-a vc-gitem-zone-height-mode-auto vc-gitem-zone-height-mode-auto-16-9 vc_gitem-is-link\" style=\"background-image: url('https:\/\/comehome.network\/wp-content\/uploads\/2024\/10\/UKRAINE-RUSSIA-CONFLICT-WAR-1024x576.jpeg') !important;\"><a href=\"https:\/\/comehome.network\/es\/einzelspende\/generadores-de-energia-vitales-para-el-invierno-de-2024\/\" title=\"Generadores de energ\u00eda vitales para el invierno de 2024\" class=\"vc_gitem-link vc-zone-link\" ><\/a><img decoding=\"async\" class=\"vc_gitem-zone-img\" src=\"https:\/\/comehome.network\/wp-content\/uploads\/2024\/10\/UKRAINE-RUSSIA-CONFLICT-WAR-1024x576.jpeg\" alt=\"Generadores de energ\u00eda vitales para el invierno de 2024\" loading=\"lazy\"><div class=\"vc_gitem-zone-mini\"><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-b vc_custom_1419240793832 vc-gitem-zone-height-mode-auto vc_gitem-is-link\"><a href=\"https:\/\/comehome.network\/es\/einzelspende\/generadores-de-energia-vitales-para-el-invierno-de-2024\/\" title=\"Generadores de energ\u00eda vitales para el invierno de 2024\" class=\"vc_gitem-link vc-zone-link\" ><\/a><div class=\"vc_gitem-zone-mini\"><\/div><\/div><\/div><div class=\"vc_gitem-zone vc_gitem-zone-c vc_custom_1419240595465\"><div class=\"vc_gitem-zone-mini\"><div class=\"vc_gitem_row vc_row vc_gitem-row-position-top\"><div class=\"vc_col-sm-12 vc_gitem-col vc_gitem-col-align-\"><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_title\" ><h4 style=\"text-align: left\" >Generadores de energ\u00eda vitales para el invierno de 2024<\/h4><\/div><div class=\"vc_custom_heading vc_gitem-post-data vc_gitem-post-data-source-post_excerpt\" ><p style=\"text-align: left\" >El invierno de 2024 volver\u00e1 a ser un desaf\u00edo extremo para muchas personas en Ucrania. La guerra rusa ha sumido al pa\u00eds en una crisis energ\u00e9tica que amenaza sobre todo a los ancianos, las familias con ni\u00f1os y los pacientes de los hospitales. En ciudades como Kharkiv y Kherson, el bombardeo constante de la infraestructura...<\/p><\/div><div class=\"vc_btn3-container  wpb_animate_when_almost_visible wpb_bounceIn bounceIn vc_btn3-left\"><a class=\"vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" a href=\"https:\/\/comehome.network\/es\/einzelspende\/generadores-de-energia-vitales-para-el-invierno-de-2024\/\" class=\"vc_gitem-link vc_general vc_btn3 vc_general vc_btn3 vc_btn3-size-lg vc_btn3-shape-square vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-blue\" target=\"_blank\" target=\"_blank\" title=\"Weiterlesen\"><i class=\"vc_btn3-icon fas fa-chevron-right\"><\/i> Weiterlesen<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_clearfix\"><\/div><\/div><\/div><\/div>\n\t<\/div>\n<\/div><div class=\"w-separator size_custom\" style=\"height:150px\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Nuestro principio rector, nuestra misi\u00f3n y nuestros socios<\/h2>\n<p>Nuestro trabajo se basa en unas directrices claras y una misi\u00f3n firme, con el apoyo de organizaciones internacionales asociadas comprometidas.<br \/>\nInf\u00f3rmate sobre los principios b\u00e1sicos que nos impulsan y los socios que nos ayudan a alcanzar nuestros objetivos.<\/p>\n<\/div><\/div><div class=\"w-separator size_large\"><\/div><div class=\"w-tabs layout_ver navwidth_auto navpos_left style_modern switch_click\" style=\"--sections-title-size:1.7em\" data-accordion-at-width=\"1024\"><div class=\"w-tabs-list items_2 align_none\" style=\"font-family:var(--h1-font-family);font-weight:500;line-height:1.7;\"><div class=\"w-tabs-list-h\"><button class=\"w-tabs-item active defined-active\" aria-controls=\"content-17205332599711720533707759\" aria-expanded=\"true\"><span class=\"w-tabs-item-title\">Directrices<\/span><\/button><button class=\"w-tabs-item\" aria-controls=\"content-17205332599711720533707759\" aria-expanded=\"false\"><span class=\"w-tabs-item-title\">Organizaciones asociadas<\/span><\/button><\/div><\/div><div class=\"w-tabs-sections titles-align_none icon_chevron cpos_right\"><div class=\"w-tabs-section active\" id=\"17205332599711720533707759\"><button class=\"w-tabs-section-header active\" aria-controls=\"content-17205332599711720533707759\" aria-expanded=\"true\"><h4 class=\"w-tabs-section-title\">Directrices<\/h4><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-17205332599711720533707759\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"g-cols wpb_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:1rem;\"><div class=\"wpb_column vc_column_container us_custom_2c4f4a12\"><div class=\"vc_column-overlay\" style=\"background:#e3e3e3\"><\/div><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Nuestra misi\u00f3n: \u00e9tica, moral y transparencia<\/h2>\n<p><strong>\u00a1Bienvenido a la Asociaci\u00f3n ComeHome!<\/strong> Nuestros principios rectores se basan en los valores fundamentales de transparencia, integridad y sostenibilidad.<br \/>\nCreemos firmemente que cada acci\u00f3n que emprendemos debe guiarse por estos valores para tener el mayor impacto positivo posible en la vida de los ni\u00f1os y sus familias.<\/p>\n<ul>\n<li><strong>Transparencia<\/strong>: Concedemos gran importancia a garantizar que nuestros fondos y recursos se gestionan con transparencia.<br \/>\nLos donantes pueden estar seguros de que sus aportaciones se utilizan de forma responsable y eficiente.<\/li>\n<li><strong>Integridad<\/strong>: Nuestras acciones se basan en principios \u00e9ticos.<br \/>\nTodos nuestros proyectos y asociaciones se examinan cuidadosamente para garantizar que cumplen las normas \u00e9ticas m\u00e1s estrictas.<\/li>\n<li><strong>Sostenibilidad<\/strong>: Nos centramos en soluciones sostenibles que tengan un impacto positivo a largo plazo.<br \/>\nNuestro objetivo no es s\u00f3lo proporcionar ayuda a corto plazo, sino provocar un cambio duradero.<\/li>\n<\/ul>\n<p>Estamos decididos a cambiar la vida de los ni\u00f1os que padecen sufrimientos y traumas inimaginables.<br \/>\nTu apoyo es crucial, y por eso queremos asegurarte que todas las donaciones que hagas se recaudar\u00e1n y se utilizar\u00e1n exclusivamente para proyectos \u00e9ticamente s\u00f3lidos.<\/p>\n<h4>Nuestra misi\u00f3n<\/h4>\n<p>Nuestra misi\u00f3n es apoyar a los ni\u00f1os que han sido deportados de su patria y permitirles regresar sanos y salvos y tener un futuro mejor.<br \/>\nAl hacerlo, concedemos gran importancia a los principios \u00e9ticos y a la integridad moral.<br \/>\nCada una de nuestras acciones se gu\u00eda por nuestros valores fundamentales de humanidad, transparencia y responsabilidad.<\/p>\n<h4>Pr\u00e1cticas \u00e9ticas de donaci\u00f3n<\/h4>\n<ul>\n<li><strong>Proyectos \u00e9ticamente s\u00f3lidos<\/strong>: S\u00f3lo recogemos donativos para proyectos que cumplen las normas \u00e9ticas m\u00e1s estrictas.<br \/>\nCada proyecto se examina cuidadosamente para garantizar que satisface las necesidades y los derechos de los ni\u00f1os y que les beneficiar\u00e1 a largo plazo.<\/li>\n<li><strong>Transparencia y supervisi\u00f3n<\/strong>: Todas las donaciones se supervisan y controlan estrictamente.<br \/>\nNos aseguramos de que cada donativo vaya exactamente donde se necesita.<br \/>\nNuestros procesos financieros son transparentes e informamos peri\u00f3dicamente sobre c\u00f3mo se utiliza el dinero.<\/li>\n<li><strong>Trabajar con socios de confianza<\/strong>: S\u00f3lo trabajamos con organizaciones reputadas y de confianza que comparten nuestros valores y comparten nuestro compromiso de apoyar y proteger a los ni\u00f1os.<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container us_custom_2c4f4a12\"><div class=\"vc_column-overlay\" style=\"background:#e3e3e3\"><\/div><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3>Por qu\u00e9 cuenta tu donativo<\/h3>\n<p>Con tu donativo, puedes contribuir directamente a mejorar la terrible situaci\u00f3n de los ni\u00f1os ucranianos deportados.<br \/>\nTu contribuci\u00f3n nos ayudar\u00e1 a proporcionar alojamiento seguro, apoyo psicol\u00f3gico, programas educativos y atenci\u00f3n m\u00e9dica.<br \/>\nCon tu apoyo, podemos dar a estos ni\u00f1os esperanza y una perspectiva de futuro.<\/p>\n<h4>Nuestra garant\u00eda para ti<\/h4>\n<p>Sabemos lo importante que es tener confianza cuando donas.<br \/>\nPor eso prometemos<\/p>\n<ul>\n<li><strong>Total transparencia<\/strong>: Siempre estar\u00e1s informado sobre c\u00f3mo se utiliza tu donaci\u00f3n.<br \/>\nLos informes y actualizaciones peri\u00f3dicos te mantienen al d\u00eda.<\/li>\n<li><strong>Uso eficiente de los fondos<\/strong>: Tu donaci\u00f3n se utiliza de forma eficiente y responsable para lograr el m\u00e1ximo impacto.<\/li>\n<li><strong>Integridad moral<\/strong>: Todas nuestras actividades y proyectos se basan en principios \u00e9ticos y morales.<br \/>\nS\u00f3lo trabajamos con socios que se adhieren a los mismos elevados est\u00e1ndares.<\/li>\n<\/ul>\n<h4>Juntos fuertes por el futuro de los ni\u00f1os<\/h4>\n<p>Tu apoyo puede marcar realmente la diferencia.<br \/>\nJuntos podemos conseguir que estos ni\u00f1os reciban la ayuda y los cuidados que tan desesperadamente necesitan.<br \/>\nAy\u00fadanos a hacer de su mundo un lugar mejor. <strong>\u00a1Haz un donativo ahora y forma parte de nuestra misi\u00f3n!<\/strong> Juntos podemos cambiar vidas y crear un futuro mejor para los ni\u00f1os.<br \/>\nTu donativo es un signo de esperanza y compasi\u00f3n. <strong>Asociaci\u00f3n ComeHome &#8211; Juntos fuertes por el futuro de los ni\u00f1os.<\/strong> \u00a1Muchas gracias por tu apoyo!<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"17205332599711720533707759\"><button class=\"w-tabs-section-header\" aria-controls=\"content-17205332599711720533707759\" aria-expanded=\"false\"><h4 class=\"w-tabs-section-title\">Organizaciones asociadas<\/h4><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-17205332599711720533707759\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"g-cols wpb_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:1rem;\"><div class=\"wpb_column vc_column_container us_custom_2c4f4a12\"><div class=\"vc_column-overlay\" style=\"background:#e3e3e3\"><\/div><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3>Organizaciones internacionales asociadas: Juntos por un futuro mejor<\/h3>\n<p><strong>Por qu\u00e9 las colaboraciones internacionales son cruciales para la<\/strong> Asociaci\u00f3n ComeHome En la Asociaci\u00f3n ComeHome, creemos firmemente que s\u00f3lo a trav\u00e9s de colaboraciones s\u00f3lidas y de confianza a nivel global podremos llevar a cabo con \u00e9xito nuestra misi\u00f3n.<br \/>\nNuestra colaboraci\u00f3n con organizaciones internacionales asociadas seleccionadas es una parte fundamental de nuestro trabajo para ofrecer el mejor apoyo posible a los ni\u00f1os ucranianos deportados.<\/p>\n<h3>Por qu\u00e9 son importantes las organizaciones internacionales asociadas<\/h3>\n<h4>1. pericia y experiencia globales<\/h4>\n<p>Nuestras organizaciones asociadas aportan una valiosa experiencia y conocimientos de distintas partes del mundo.<br \/>\nTienen amplios conocimientos y m\u00e9todos probados para ayudar a ni\u00f1os y familias en situaciones de crisis.<br \/>\nEsta perspectiva global nos permite adoptar y aplicar las mejores pr\u00e1cticas para ofrecer soluciones eficaces y sostenibles.<\/p>\n<h4>2. puesta en com\u00fan de recursos<\/h4>\n<p>Las asociaciones internacionales nos permiten aunar recursos y utilizarlos con mayor eficacia.<br \/>\nAl trabajar con organizaciones de renombre, podemos maximizar los recursos financieros, los recursos tecnol\u00f3gicos y la experiencia humana.<br \/>\nEsto aumenta el impacto de nuestros proyectos y garantiza que la ayuda llegue r\u00e1pida y eficazmente a quienes la necesitan.<\/p>\n<h4>3. gama m\u00e1s amplia<\/h4>\n<p>Trabajando con socios internacionales, podemos ampliar considerablemente nuestro alcance.<br \/>\nEstos socios han establecido redes y tienen acceso a comunidades a las que no podr\u00edamos llegar por nuestra cuenta.<br \/>\nEsto es especialmente importante para garantizar que nuestra ayuda llega a los ni\u00f1os y familias m\u00e1s remotos y vulnerables.<\/p>\n<h4>4 Misi\u00f3n y valores comunes<\/h4>\n<p>Nuestras organizaciones asociadas comparten nuestra visi\u00f3n y nuestros valores.<br \/>\nAl igual que nosotros, est\u00e1n convencidas de que todos los ni\u00f1os tienen derecho a la seguridad, a la educaci\u00f3n y a un futuro esperanzador.<br \/>\nEsta misi\u00f3n compartida refuerza nuestra cooperaci\u00f3n y promueve una colaboraci\u00f3n eficaz y basada en la confianza.<\/p>\n<h4>Por qu\u00e9 es importante tu apoyo<\/h4>\n<p>Con tu apoyo, podremos seguir ampliando y reforzando nuestras asociaciones.<br \/>\nTu donativo nos ayudar\u00e1, junto con nuestros socios internacionales, a financiar programas de ayuda integrales que ofrezcan apoyo directo y sostenible a los ni\u00f1os afectados y a sus familias.<\/p>\n<h4>Juntos podemos conseguir m\u00e1s.<\/h4>\n<p>Tu donativo marca la diferencia y contribuye a garantizar que nuestras asociaciones internacionales puedan seguir funcionando con \u00e9xito y lograr todo su impacto. <strong>Ap\u00f3yanos a nosotros y a nuestras organizaciones asociadas para crear un futuro mejor para los ni\u00f1os ucranianos.<\/strong><\/p>\n<p><strong>Asociaci\u00f3n ComeHome &#8211; Juntos fuertes por el futuro de los ni\u00f1os.<\/strong> \u00a1Muchas gracias por tu valioso apoyo!<\/p>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container us_custom_2c4f4a12\"><div class=\"vc_column-overlay\" style=\"background:#e3e3e3\"><\/div><div class=\"vc_column-inner\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Dar esperanza, asegurar el futuro &#8211; \u00a1Apoya a ComeHome! Haciendo el mundo un poco mejor &#8211; mano a mano por un futuro mejor &#8211; \u00a1dona ahora! donaci\u00f3n segura Tu apoyo espec\u00edfico a proyectos probados e importantes \u00a1Bienvenido a la Asociaci\u00f3n ComeHome! Entendemos que cada donante tiene diferentes preocupaciones y preferencias en cuanto al destino de...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"give_campaign_id":0,"pmpro_default_level":"","episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","iawp_total_views":2,"footnotes":""},"class_list":["post-4211","page","type-page","status-publish","hentry","pmpro-has-access"],"acf":[],"campaignId":"","_links":{"self":[{"href":"https:\/\/comehome.network\/es\/wp-json\/wp\/v2\/pages\/4211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comehome.network\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/comehome.network\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/comehome.network\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comehome.network\/es\/wp-json\/wp\/v2\/comments?post=4211"}],"version-history":[{"count":12,"href":"https:\/\/comehome.network\/es\/wp-json\/wp\/v2\/pages\/4211\/revisions"}],"predecessor-version":[{"id":7525,"href":"https:\/\/comehome.network\/es\/wp-json\/wp\/v2\/pages\/4211\/revisions\/7525"}],"wp:attachment":[{"href":"https:\/\/comehome.network\/es\/wp-json\/wp\/v2\/media?parent=4211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}